{"id":4079,"date":"2018-04-25T10:04:28","date_gmt":"2018-04-25T13:04:28","guid":{"rendered":"https:\/\/bernard.com.br\/biblioteca\/"},"modified":"2022-06-02T20:45:47","modified_gmt":"2022-06-02T23:45:47","slug":"biblioteca","status":"publish","type":"page","link":"https:\/\/bernard.com.br\/es\/contenido\/biblioteca\/","title":{"rendered":"Biblioteca"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space height=\u00bb5&#8243;][vc_column_text]<\/p>\n<blockquote>\n<h5 style=\"text-align: justify;\">Si usted es cliente de Bernard y desea poner sus propios trabajos cient\u00edficos en nuestra biblioteca, p\u00f3ngase en contacto con el e-mail\u00a0<a href=\"mailto:biblioteca@bernard.com.br\">biblioteca@bernard.com.br<\/a><\/h5>\n<\/blockquote>\n<p>[\/vc_column_text]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard-Assessing_Individual_Performance_in_a_Total_Enterprise_Simulation.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4094\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4094 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2004)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4094 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Assessing Individual Performance in a Total Enterprise Simulation<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard-Characterizing_Business_Games_Used_in_Distance_Education.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5009\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5009 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2006)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5009 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Characterizing Business Games Used in Distance Education<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard-Mapeamento_do_Uso_de_Jogos_no_Brasil_e_Avaliacoes_de_uma_Aplicacao.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5068\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5068 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2006)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5068 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Mapeamento do Uso de Jogos no Brasil e Avalia\u00e7\u00f5es de uma Aplica\u00e7\u00e3o<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Capitulo_Bernard_Livro_Eliezer-Jogos_de_Empresas_para_Capacitacao_Estrategica_e_Simulacao_Gerencial.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2968\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-2968 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2007)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2968 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Jogos de Empresas para Capacita\u00e7\u00e3o Estrat\u00e9gica e Simula\u00e7\u00e3o Comercial<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard-Students_Perceptions_on_the_Individual_Managerial_Performance.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7749\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7749 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2007)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7749 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Students&#8217; Perceptions on the Individual Managerial Performance<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard-Utilizacao_de_um_Ambiente_Virtual_de_Aprendizagem_em_um_Curso_Presencial_de_Simulacao_Gerencial.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5022\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5022 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2010)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5022 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Utiliza\u00e7\u00e3o de Ambiente Virtual de Aprendizagem em Curso Presencial de Simula\u00e7\u00e3o Gerencial<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard-Merger_of_Companies_in_Business_Game_Exercise.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8717\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8717 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2012)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8717 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Merger of Companies in Business Game Exercise<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard-Using_an_Investment_Fund_Simulation_Integrated_with_a_Business_Game.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1762\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-1762 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S. (2013)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1762 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p><span id=\"title\" title=\"Using an Investment Fund Simulation Integrated with a Business Game\">Using an Investment Fund Simulation Integrated with a Business Game<\/span><\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard_et_al-O_Uso_de_Sistemas_de_Apoio_as_Decisoes_em_Cursos_de_Simulacao_Empresarial.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9559\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-9559 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S.; BERNARD, Paul L. S.; BERNARD, Rosilane P. (2004)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9559 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>O Uso de Sistemas de Apoio \u00e0s Decis\u00f5es em Cursos de Simula\u00e7\u00e3o Empresarial<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard_et_al-A_Relevancia_dos_Custos_na_Formacao_do_Preco_de_Venda.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3453\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-3453 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S.; BORGERT, Altair; DIAS, Jos\u00e9 S.; SOUZA, Mois\u00e9s P. (2007)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3453 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>A Relev\u00e2ncia dos Custos na Forma\u00e7\u00e3o do Pre\u00e7o de Venda<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard&#038;Cannon-Exploring_Motivation_Using_Emoticons_to_Map_Student_Motivation_in_a_Business_Games_Exercise.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5423\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5423 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S.; CANNON, Hugh M. (2011)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5423 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Exploring Motivation: Using Emoticons to Map Student Motivation in a Business Game Exercise<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard&#038;Souza_Filho-Simulacao_Gerencial_Uma_Proposta_de_Introducao_e_Adequacao_do_Metodo_aos_Cursos_de_Graduacao_em_Administracao_e_Ciencias_Contabeis.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4469\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4469 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S.; SOUZA FILHO, Jos\u00e9 C. (2007)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4469 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Simula\u00e7\u00e3o Gerencial: Uma Proposta para os Cursos de Gradua\u00e7\u00e3o em Administra\u00e7\u00e3o e Ci\u00eancias Cont\u00e1beis<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard&#038;Souza-Dominance_in_Online_Business_Games_Competitions.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7410\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7410 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S.; SOUZA, Mois\u00e9s P. (2009)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7410 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Dominance in Online Business Games Competitions<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Bernard_et_al-Evaluation_Model_of_the_Global_Performance_of_a_Management_Simulation_for_the_Academic_Environment.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5657\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5657 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">BERNARD, Ricardo R. S.; SOUZA, Mois\u00e9s P.; LYRIO, Maur\u00edcio V. L. (2008)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5657 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Evaluation Model of the Global Performance of a Management Simulation for the Academic Environment<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Tese_Costa-Matriz_de_Jogos_Estrategicos_Novo_Modelo_para_Representacao_e_Estudo_de_Conflito_de_Interesses.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1901\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-1901 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">COSTA, Eliezer A. (2008)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1901 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Matriz de Jogos Estrat\u00e9gicos \u2013 Novo Modelo para Representa\u00e7\u00e3o e Estudo de Conflito de Interesses<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Dias-Junior_et_al-Previsao-de-Demanda-Um-Experimento-em-Ambiente-Simulado.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7202\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7202 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">DIAS JUNIOR, Claudelino M.; COSTA, P\u00e2mella D.; GUIMAR\u00c3ES, Rafael P.; SOUZA, Gueibe P. (2017)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7202 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Previs\u00e3o de Demanda: um experimento em ambiente simulado<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Gimenes&#038;Bernard-Simulacao_Empresarial_no_Ensino_da_Contabilidade_Gerencial.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4354\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4354 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">GIMENES, R\u00e9gio M. T.; BERNARD, Ricardo R. S. (2001)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4354 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Simula\u00e7\u00e3o Empresarial no Ensino da Contabilidade Gerencial<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Hoffmann_et_al-Importancia_dos_Jogos_Empresariais_no_Perfil_do_Administrador_Contemporaneo.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2030\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-2030 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">HOFFMANN, Arilson; FROELLICH, Anderson; SGUAREZI, Sandro; NUNES, Edin\u00e9ia; LIMA, Ana (2014)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2030 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>A Import\u00e2ncia dos Jogos Empresariais na Constru\u00e7\u00e3o do Perfil do Administrador Contempor\u00e2neo<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Roncalio&#038;Bernard-Um_Modelo_de_Simulacao_para_o_Ensino_de_Contabilidade_Publica_no_Brasil.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6413\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-6413 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">RONCALIO, Michele P.; BERNARD, Ricardo R. S. (2008)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6413 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Um Modelo de Simula\u00e7\u00e3o para o Ensino de Contabilidade P\u00fablica no Brasil<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Dissertacao_Souza-Capacidade_Preditiva_e_Desempenho_Gerencial_em_Jogos_de_Negocios.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6781\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-6781 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">SOUZA, Mois\u00e9s P. (2009)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6781 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Capacidade Preditiva e Desempenho Gerencial em Jogos de Neg\u00f3cios<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:60px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:20px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-download\" ><\/i><a class=\"ulimate-info-list-link\" href=\"http:\/\/ww2.websimulador.com.br\/arquivos\/referencia\/Artigo_Pacheco_et_al-Another_Look_at_the_Use_of_Forecasting_Accuracy_on_the_Business_Simulation_Games.pdf\" target=\"_blank\" rel=\"noopener\" ><\/a><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9706\" style=\"font-size:20px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-9706 span'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:25px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\">SOUZA, Mois\u00e9s P.; BERNARD, Ricardo R. S.; CANNON, Hugh M. (2010)<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9706 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:23px;\"}'  style=\"font-family:&#039;Open Sans&#039;;\"><p>Another Look at the Use of Forecasting Accuracy on the Business Simulation Games<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=\u00bb5&#8243;][vc_column_text] Si usted es cliente de Bernard y desea poner sus propios trabajos cient\u00edficos en nuestra biblioteca, p\u00f3ngase en contacto con el e-mail\u00a0biblioteca@bernard.com.br [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5963,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-4079","page","type-page","status-publish","hentry","description-off"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/pages\/4079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/comments?post=4079"}],"version-history":[{"count":1,"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/pages\/4079\/revisions"}],"predecessor-version":[{"id":4830,"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/pages\/4079\/revisions\/4830"}],"up":[{"embeddable":true,"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/pages\/5963"}],"wp:attachment":[{"href":"https:\/\/bernard.com.br\/es\/wp-json\/wp\/v2\/media?parent=4079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}